{"id":31,"count":0,"description":"","link":"https:\/\/www.bioescuela.es\/en\/actividad-categoria\/planes-en-familia\/","name":"Planes en familia","slug":"planes-en-familia","taxonomy":"actividad_categoria","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Planes en familia archivos - Bioescuela La Hornera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bioescuela.es\/en\/actividad-categoria\/planes-en-familia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Planes en familia archivos - Bioescuela La Hornera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bioescuela.es\/en\/actividad-categoria\/planes-en-familia\/\" \/>\n<meta property=\"og:site_name\" content=\"Bioescuela La Hornera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/actividad-categoria\\\/planes-en-familia\\\/\",\"url\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/actividad-categoria\\\/planes-en-familia\\\/\",\"name\":\"Planes en familia archivos - Bioescuela La Hornera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/actividad-categoria\\\/planes-en-familia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/actividad-categoria\\\/planes-en-familia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Planes en familia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/\",\"name\":\"Bioescuela La Hornera\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/#organization\",\"name\":\"Bioescuela La Hornera\",\"url\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bioescuela.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/bioescuela-color.svg\",\"contentUrl\":\"https:\\\/\\\/www.bioescuela.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/bioescuela-color.svg\",\"width\":450,\"height\":347,\"caption\":\"Bioescuela La Hornera\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioescuela.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100064240171160\",\"https:\\\/\\\/www.instagram.com\\\/bioescuelalahornera\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Planes en familia archivos - Bioescuela La Hornera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bioescuela.es\/en\/actividad-categoria\/planes-en-familia\/","og_locale":"en_US","og_type":"article","og_title":"Planes en familia archivos - Bioescuela La Hornera","og_url":"https:\/\/www.bioescuela.es\/en\/actividad-categoria\/planes-en-familia\/","og_site_name":"Bioescuela La Hornera","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bioescuela.es\/en\/actividad-categoria\/planes-en-familia\/","url":"https:\/\/www.bioescuela.es\/en\/actividad-categoria\/planes-en-familia\/","name":"Planes en familia archivos - Bioescuela La Hornera","isPartOf":{"@id":"https:\/\/www.bioescuela.es\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.bioescuela.es\/en\/actividad-categoria\/planes-en-familia\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bioescuela.es\/en\/actividad-categoria\/planes-en-familia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.bioescuela.es\/en\/"},{"@type":"ListItem","position":2,"name":"Planes en familia"}]},{"@type":"WebSite","@id":"https:\/\/www.bioescuela.es\/en\/#website","url":"https:\/\/www.bioescuela.es\/en\/","name":"Bioescuela La Hornera","description":"","publisher":{"@id":"https:\/\/www.bioescuela.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bioescuela.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bioescuela.es\/en\/#organization","name":"Bioescuela La Hornera","url":"https:\/\/www.bioescuela.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bioescuela.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.bioescuela.es\/wp-content\/uploads\/2023\/02\/bioescuela-color.svg","contentUrl":"https:\/\/www.bioescuela.es\/wp-content\/uploads\/2023\/02\/bioescuela-color.svg","width":450,"height":347,"caption":"Bioescuela La Hornera"},"image":{"@id":"https:\/\/www.bioescuela.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100064240171160","https:\/\/www.instagram.com\/bioescuelalahornera"]}]}},"_links":{"self":[{"href":"https:\/\/www.bioescuela.es\/en\/wp-json\/wp\/v2\/actividad_categoria\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bioescuela.es\/en\/wp-json\/wp\/v2\/actividad_categoria"}],"about":[{"href":"https:\/\/www.bioescuela.es\/en\/wp-json\/wp\/v2\/taxonomies\/actividad_categoria"}],"wp:post_type":[{"href":"https:\/\/www.bioescuela.es\/en\/wp-json\/wp\/v2\/actividad?actividad_categoria=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}